{"id":72,"date":"2023-08-25T14:16:59","date_gmt":"2023-08-25T12:16:59","guid":{"rendered":"https:\/\/limodor-ch.dev-web.at\/allgemeine_geschaeftsbedingungen\/"},"modified":"2024-09-09T14:11:36","modified_gmt":"2024-09-09T12:11:36","slug":"allgemeine_geschaeftsbedingungen","status":"publish","type":"page","link":"https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/","title":{"rendered":"Allgemeine Gesch\u00e4ftsbedingungen"},"content":{"rendered":"\n<div class=\"row\"  id=\"row-207099267\">\n\n\n\t<div id=\"col-637872905\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1290996217\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1290996217 {\n  padding-top: 60px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h1>Allgemeine Gesch\u00e4ftsbedingungen<\/h1>\n<div class=\"row\"  id=\"row-823609435\">\n\n\n\t<div id=\"col-1456712117\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<ul>\n<li>\n<h5><a href=\"#AGB1\">1. Geltungsbereich<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB2\">2. Angebot und Vertragsabschlus<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB3\">3. Preise<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB4\">4. Bestellung und Lieferung<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB5\">5. Annahmeverzug<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB6\">6. Gefahren\u00fcbergang<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB7\">7. Zahlung<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB8\">8. Zahlungsverzug<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB9\">9. Eigentumsvorbehalt<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB10\" data-wplink-edit=\"true\">10. Exportkontrolle<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB11\">11. \u00c4nderung der Bestellung oder Stornierung<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB12\">12. Garantie<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB13\">13. Retouren<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB14\">14. Haftung<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB15\">15. Datenschutz<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB16\">16. Gerichtsstand und anwendbares Recht<\/a><\/h5>\n<\/li>\n<li>\n<h5><a href=\"#AGB17\">17. Schlussbestimmungen<\/a><\/h5>\n<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1661322348\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row row-small\"  id=\"row-1821343922\">\n\n\n\t<div id=\"col-1982925551\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #1.-geltungsbereich\" data-bullet=\"false\" data-link=\"#1.-geltungsbereich\" data-title=\"1. Geltungsbereich\" ><a name=\"1.-geltungsbereich\"><\/a><\/span>\n\n<h4 id=\"AGB1\">1. Geltungsbereich<\/h4>\n<p>Die Lieferungen, Leistungen und Angebote der LIMODOR L\u00fcftungstechnik AG (CHE-314.289.558 MWST), Zielstrasse 13, 9050 Appenzell, nachstehend LIMODOR, erfolgen ausschliesslich aufgrund dieser allgemeinen Gesch\u00e4ftsbedingungen, auch wenn sie nicht nochmals ausdr\u00fccklich vereinbart werden. Mit Bestellung der Ware oder Leistung gelten diese Bedingungen als angenommen. Allgemeinen Einkaufsbedingungen des Kunden werden hiermit widersprochen.<\/p>\n<p>Abweichungen von den allgemeinen Gesch\u00e4ftsbedingungen sind nur wirksam, wenn diese von LIMODOR schriftlich best\u00e4tigt werden.<\/p>\n<p>LIMODOR beh\u00e4lt sich das Recht vor, diese AGB jederzeit zu \u00e4ndern. Massgebend ist jeweils die zum Zeitpunkt der Bestellung geltende Version dieser AGB, welche f\u00fcr diese Bestellung nicht einseitig ge\u00e4ndert werden k\u00f6nnen. Entgegenstehende oder von diesen AGB abweichende Bedingungen der Kundschaft werden nicht anerkannt.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1829949126\">\n\n\n\t<div id=\"col-1184339088\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #2.-angebot-und-vertragsabschluss\" data-bullet=\"false\" data-link=\"#2.-angebot-und-vertragsabschluss\" data-title=\"2. Angebot und Vertragsabschluss\" ><a name=\"2.-angebot-und-vertragsabschluss\"><\/a><\/span>\n\n<h4 id=\"AGB2\">2. Angebot und Vertragsabschluss<\/h4>\n<p>Die Angebote von LIMODOR in Preislisten und Inseraten stellen kein rechtlich bindendes Angebot dar, sondern eine Aufforderung an den Kunden, einen f\u00fcr diese verbindlichen Bestellungen\u2009\/\u2009Offerte abzugeben.<\/p>\n<p>Massgebend f\u00fcr das Zustandekommen des Kaufvertrags ist der Preis in der Offerte zum Zeitpunkt der Bestellung. Schriftliche Offerten sind ab Offertdatum f\u00fcr einen Monat verbindlich und gelten nur bei termingem\u00e4sser und geschlossener Abnahme der offerierten Mengen.<\/p>\n<p>Die Angaben in den Verkaufsunterlagen (Zeichnungen, Abbildungen, Masse, Gewichte und sonstige Leistungen) sind als Richtwerte zu verstehen und stellen keine Zusicherungen von Eigenschaften dar, es sei denn, sie werden schriftlich ausdr\u00fccklich als verbindlich bezeichnet.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-205227112\">\n\n\n\t<div id=\"col-1327800718\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #3.-preise\" data-bullet=\"false\" data-link=\"#3.-preise\" data-title=\"3. Preise\" ><a name=\"3.-preise\"><\/a><\/span>\n\n<h4 id=\"AGB3\">3. Preise<\/h4>\n<p>Alle Verkaufspreise verstehen sich exkl. MwSt., Versand-, Transport- und Versicherungskosten, jedoch inkl. Verpackung.<\/p>\n<p>LIMODOR beh\u00e4lt sich das Recht vor, die Preise der angebotenen Produkte und Dienstleistungen jederzeit zu \u00e4ndern.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1092330832\">\n\n\n\t<div id=\"col-1960972452\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #4.-bestellung-und-lieferung\" data-bullet=\"false\" data-link=\"#4.-bestellung-und-lieferung\" data-title=\"4. Bestellung und Lieferung\" ><a name=\"4.-bestellung-und-lieferung\"><\/a><\/span>\n\n<h4 id=\"AGB4\">4. Bestellung und Lieferung<\/h4>\n<p>Bestellungen werden per E-Mail oder telefonisch entgegengenommen. Wird nach der Bestelleingangsbest\u00e4tigung festgestellt, dass ein Artikel nicht lieferbar ist, wird die entsprechende Bestellung storniert. Weitergehende Anspr\u00fcche kann der Kunde nicht gegen LIMODOR geltend machen.<\/p>\n<p>Die in der Offerte genannte Lieferfrist gilt als Richtwert und ist nicht verbindlich. Sollte eine Lieferfrist durch LIMODOR nicht eingehalten werden k\u00f6nnen, so kann der Kunde ab 30 Tagen nach der Bestelleingangsbest\u00e4tigung nach schriftlicher Mitteilung an den Kundendienst von der Bestellung zur\u00fccktreten.<\/p>\n<p>LIMODOR ist zu Teillieferungen berechtigt. Kann ein Teil der bestellten Ware nicht geliefert werden, so besteht kein Recht auf Stornierung der gesamten Bestellung. Weitergehende Anspr\u00fcche kann der Kunde nicht geltend machen.<\/p>\n<p>Die Lieferung erfolgt ausschliesslich an Adressen in der Schweiz und im F\u00fcrstentum Liechtenstein auf Kosten und Gefahr des Kunden. Grunds\u00e4tzlich wird nur an das Postfach bzw. die Bordsteinkante des Kunden geliefert.<\/p>\n<p>Der Kunde verpflichtet sich, die angelieferte\u2009\/\u2009abgeholte Ware sofort auf Richtigkeit, Vollst\u00e4ndigkeit und Unversehrtheit zu \u00fcberpr\u00fcfen. Sch\u00e4den an der gelieferten\u2009\/\u2009abgeholten Ware m\u00fcssen schnellstm\u00f6glich, sp\u00e4testens aber f\u00fcnf Kalendertage nach Anlieferung, dem ausf\u00fchrenden Transportunternehmen und LIMODOR gemeldet werden. Bei Beanstandungen m\u00fcssen s\u00e4mtliche Teile samt der Originalverpackung aufbewahrt werden und d\u00fcrfen erst nach schriftlicher Zustimmung des Transportunternehmens und von LIMODOR entsorgt werden.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1847716078\">\n\n\n\t<div id=\"col-1992819552\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #5.-annahmeverzug\" data-bullet=\"false\" data-link=\"#5.-annahmeverzug\" data-title=\"5. Annahmeverzug\" ><a name=\"5.-annahmeverzug\"><\/a><\/span>\n\n<h4 id=\"AGB5\">5. Annahmeverzug<\/h4>\n<p>Bestellungen werden per E-Mail oder telefonisch entgegengenommen. Wird nach der Bestelleingangsbest\u00e4tigung festgestellt, dass ein Artikel nicht lieferbar ist, wird die entsprechende Bestellung storniert. Weitergehende Anspr\u00fcche kann der Kunde nicht gegen LIMODOR geltend machen.<\/p>\n<p>Die in der Offerte genannte Lieferfrist gilt als Richtwert und ist nicht verbindlich. Sollte eine Lieferfrist durch LIMODOR nicht eingehalten werden k\u00f6nnen, so kann der Kunde ab 30 Tagen nach der Bestelleingangsbest\u00e4tigung nach schriftlicher Mitteilung an den Kundendienst von der Bestellung zur\u00fccktreten.<\/p>\n<p>LIMODOR ist zu Teillieferungen berechtigt. Kann ein Teil der bestellten Ware nicht geliefert werden, so besteht kein Recht auf Stornierung der gesamten Bestellung. Weitergehende Anspr\u00fcche kann der Kunde nicht geltend machen.<\/p>\n<p>Die Lieferung erfolgt ausschliesslich an Adressen in der Schweiz und im F\u00fcrstentum Liechtenstein auf Kosten und Gefahr des Kunden. Grunds\u00e4tzlich wird nur an das Postfach bzw. die Bordsteinkante des Kunden geliefert.<\/p>\n<p>Der Kunde verpflichtet sich, die angelieferte\u2009\/\u2009abgeholte Ware sofort auf Richtigkeit, Vollst\u00e4ndigkeit und Unversehrtheit zu \u00fcberpr\u00fcfen. Sch\u00e4den an der gelieferten\u2009\/\u2009abgeholten Ware m\u00fcssen schnellstm\u00f6glich, sp\u00e4testens aber f\u00fcnf Kalendertage nach Anlieferung, dem ausf\u00fchrenden Transportunternehmen und LIMODOR gemeldet werden. Bei Beanstandungen m\u00fcssen s\u00e4mtliche Teile samt der Originalverpackung aufbewahrt werden und d\u00fcrfen erst nach schriftlicher Zustimmung des Transportunternehmens und von LIMODOR entsorgt werden.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1024006310\">\n\n\n\t<div id=\"col-687404146\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #6.-gefahren\u00fcbergang\" data-bullet=\"false\" data-link=\"#6.-gefahren\u00fcbergang\" data-title=\"6. Gefahren\u00fcbergang\" ><a name=\"6.-gefahren\u00fcbergang\"><\/a><\/span>\n\n<h4 id=\"AGB6\">6. Gefahren\u00fcbergang<\/h4>\n<p>Die Gefahr geht auf den Kunden \u00fcber, sobald die Sendung an das f\u00fcr den Transport ausf\u00fchrende Unternehmen \u00fcbergeben worden ist. Falls der Versand sich ohne Verschulden von LIMODOR verz\u00f6gert oder unm\u00f6glich wird, geht die Gefahr mit der Meldung der Versandbereitschaft auf den Kunden \u00fcber. Eine im Einzelfall vereinbarte \u00dcbernahme der Transportkosten durch LIMODOR hat keinen Einfluss auf den Gefahren\u00fcbergang.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-725439017\">\n\n\n\t<div id=\"col-551003530\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #7.-zahlung\" data-bullet=\"false\" data-link=\"#7.-zahlung\" data-title=\"7. Zahlung\" ><a name=\"7.-zahlung\"><\/a><\/span>\n\n<h4 id=\"AGB7\">7. Zahlung<\/h4>\n<p>Alle Zahlungsforderungen von Produkten und Dienstleistungen macht LIMODOR direkt bei der Kundschaft geltend. LIMODOR beh\u00e4lt sich das Recht vor, Bonit\u00e4tsabkl\u00e4rungen \u00fcber den Kunden einzuholen und kann zu diesem Zweck Kundendaten an Dritte weiterleiten.<br \/>Zahlungen m\u00fcssen in Schweizer Franken geleistet werden.<\/p>\n<p>Es besteht keine Vorleistungspflicht von LIMODOR. Bei Kauf auf Rechnung ist der Kunde verpflichtet, den Rechnungsbetrag innert 30 Kalendertagen nach Erhalt der Lieferung ohne jeglichen (Skonto-) Abzug zu begleichen. Im Falle einer teilweise erfolgten R\u00fccksendung der gelieferten Produkte kann der Rechnungsbetrag entsprechend reduziert werden.<\/p>\n<p>Werden nach Vertragsabschluss Umst\u00e4nde bekannt, die geeignet sind, die Kreditw\u00fcrdigkeit des Kunden zu mindern, ist LIMODOR berechtigt, noch ausstehende Leistungen nur gegen Vorauszahlung oder Sicherheitsleistungen auszuf\u00fchren, sowie nach Ablauf einer angemessenen Nachfrist vom Vertrag zur\u00fcckzutreten. Die Zur\u00fcckhaltung von Zahlungen zwecks Verrechnung mit nicht ausdr\u00fccklich von uns anerkannter Anspr\u00fcchen des Kunden ist nicht gestattet.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1979634044\">\n\n\n\t<div id=\"col-1753979618\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #8.-zahlungsverzug\" data-bullet=\"false\" data-link=\"#8.-zahlungsverzug\" data-title=\"8. Zahlungsverzug\" ><a name=\"8.-zahlungsverzug\"><\/a><\/span>\n\n<h4 id=\"AGB8\">8. Zahlungsverzug<\/h4>\n<p>Kommt der Kunde seinen Zahlungsverpflichtungen ganz oder teilweise nicht nach, werden alle offenen Betr\u00e4ge, welche der Kunde LIMODOR unter irgendeinem Titel schuldet, sofort (bei Vorauszahlung innert 8 Kalendertagen seit der 1. Mahnung) f\u00e4llig und LIMODOR kann diese sofort einfordern und weitere Lieferungen von Produkten an die Kundschaft einstellen.<\/p>\n<p>Ab Eintritt des Verzugs ist LIMODOR ein Zins von 10\u2009% pro Jahr geschuldet. F\u00fcr die zweite und f\u00fcr die dritte Mahnung sind Umtriebsentsch\u00e4digungen im Betrag von je CHF 20.\u2013 geschuldet.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-152958481\">\n\n\n\t<div id=\"col-143551438\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #9.-eigentumsvorbehalt\" data-bullet=\"false\" data-link=\"#9.-eigentumsvorbehalt\" data-title=\"9. Eigentumsvorbehalt\" ><a name=\"9.-eigentumsvorbehalt\"><\/a><\/span>\n\n<h4 id=\"AGB9\">9. Eigentumsvorbehalt<\/h4>\n<p>Bestellte Produkte bleiben bis zur vollst\u00e4ndigen Bezahlung an LIMODOR im Eigentum von LIMODOR. LIMODOR ist berechtigt, einen entsprechenden Eintrag im Eigentumsvorbehaltsregister vorzunehmen. Vor Eigentums\u00fcbergang ist eine Verpf\u00e4ndung, Sicherungs\u00fcbereignung, Verarbeitung oder Umgestaltung ohne ausdr\u00fcckliche Einwilligung von LIMODOR nicht zul\u00e4ssig.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1826222869\">\n\n\n\t<div id=\"col-1013167187\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #10.-exportkontrolle\" data-bullet=\"false\" data-link=\"#10.-exportkontrolle\" data-title=\"10. Exportkontrolle\" ><a name=\"10.-exportkontrolle\"><\/a><\/span>\n\n<h4 id=\"AGB10\">10. Exportkontrolle<\/h4>\n<p>Der Kunde ist mit Bezug auf alle von LIMODOR bezogenen Produkte alleine verantwortlich f\u00fcr die sorgf\u00e4ltige Abkl\u00e4rung und vollst\u00e4ndige Einhaltung der gesetzlichen Vorschriften zur Exportkontolle (inkl. G\u00fcterkontrolle, Sanktionen, Embargos, etc.). Der Kunde tr\u00e4gt f\u00fcr diese Abkl\u00e4rung und Einhaltung die Beweislast und ist bei jedem Verstoss verpflichtet, LIMODOR f\u00fcr alle resultierenden Anspr\u00fcche, Sch\u00e4den und Einbussen vollst\u00e4ndig schadlos zu halten.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1519082716\">\n\n\n\t<div id=\"col-79488532\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #11.-\u00c4nderung-der-bestellung-oder-stornierung\" data-bullet=\"false\" data-link=\"#11.-\u00c4nderung-der-bestellung-oder-stornierung\" data-title=\"11. \u00c4nderung der Bestellung oder Stornierung\" ><a name=\"11.-\u00c4nderung-der-bestellung-oder-stornierung\"><\/a><\/span>\n\n<h4 id=\"AGB11\">11. \u00c4nderung der Bestellung oder Stornierung<\/h4>\n<p>Bestellungen verpflichten die Kundschaft zur Abnahme der Produkte und Leistungen. Nachtr\u00e4gliche \u00c4nderungen oder Stornierungen von Bestellungen der Kundschaft kann LIMODOR nach freiem Ermessen akzeptieren und eine Umtriebs-Entsch\u00e4digung von 20\u2009% des stornierten Bestellwerts, mindestens aber CHF 60.\u2013, sowie den allf\u00e4lligen Wertverlust der stornierten Produkte seit deren Bestellung in Rechnung stellen.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1875396160\">\n\n\n\t<div id=\"col-583178374\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #12.-garantie\" data-bullet=\"false\" data-link=\"#12.-garantie\" data-title=\"12. Garantie\" ><a name=\"12.-garantie\"><\/a><\/span>\n\n<h4 id=\"AGB12\">12. Garantie<\/h4>\n<p>LIMODOR gew\u00e4hrt f\u00fcr ungebraucht gelieferte Produkte eine Garantie von zwei Jahren f\u00fcr M\u00e4ngelfreiheit und Funktionsf\u00e4higkeit des bestellten Produktes. Unwesentliche Abweichungen von zugesicherten Eigenschaften und Verschleissteile (wie Verbrauchsmaterial, Zubeh\u00f6r, Batterien und Akkus) sind von der Garantie ausgenommen.<\/p>\n<p>Die Garantiefrist von zwei Jahren beginnt zum Zeitpunkt der Auslieferung jedes Produktes zu laufen. Der Lieferschein gilt als Garantieschein und ist sorgf\u00e4ltig aufzubewahren. Erfolgt eine Nachbesserung oder Ersatzleistung, verl\u00e4ngert sich die Garantiefrist nicht.<\/p>\n<p>Werden die Betriebs- oder Wartungsanweisungen nicht befolgt, \u00c4nderungen vorgenommen, Teile ausgewechselt oder Verbrauchsmaterialien verwendet, die nicht den Originalspezifikationen entsprechen, so entf\u00e4llt die Garantie, soweit der Mangel hierauf zur\u00fcckzuf\u00fchren ist. Dies gilt auch, soweit ein Mangel auf unsachgem\u00e4sse Benutzung, Lagerung und Handhabung der Ger\u00e4te, oder Fremdeingriff sowie das \u00d6ffnen von Ger\u00e4ten zur\u00fcckzuf\u00fchren ist.<\/p>\n<p>Der Kunde hat im Garantiefall Anspruch auf Reparatur, Ersatzleistung oder R\u00fccknahme. Die Wahl \u00fcber die Art der M\u00e4ngelbehebung liegt bei LIMODOR oder dem Hersteller. Entscheidet sich LIMODOR oder der Hersteller f\u00fcr die R\u00fccknahme, erfolgt die R\u00fcckverg\u00fctung an den Kunden nach dem Zeitwert des defekten Ger\u00e4ts. W\u00e4hrend der Dauer einer M\u00e4ngelbehebung besteht kein Anspruch auf ein kostenloses Ersatzger\u00e4t.<\/p>\n<p>Weitergehende Anspr\u00fcche sowie die gesetzlichen Bestimmungen zur Gew\u00e4hrleistung werden ausgeschlossen. Ausgeschlossen ist insbesondere jeder Ersatzanspruch f\u00fcr indirekten Schaden, mittelbaren<br \/>Schaden, Mangelfolgeschaden, Drittkosten etc.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1220406381\">\n\n\n\t<div id=\"col-1667388905\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #13.-retouren\" data-bullet=\"false\" data-link=\"#13.-retouren\" data-title=\"13. Retouren\" ><a name=\"13.-retouren\"><\/a><\/span>\n\n<h4 id=\"AGB13\">13. Retouren<\/h4>\n<p>Der Kunde hat kein R\u00fccktritts-, R\u00fcckgabe-, oder Umtauschrecht in Bezug auf bestellte und m\u00e4ngelfrei gelieferte oder zur Lieferung angebotene Ware.<\/p>\n<p>Eine R\u00fccknahme durch LIMODOR aufgrund besonderer Absprache ist ausschliesslich bis zwei Wochen (14 Kalendertage) nach Erhalt der Ware m\u00f6glich, massgebend ist das Datum der Zustellung bzw. Abholung. Der Kunde ist in jedem Fall daf\u00fcr verantwortlich, die zu retournierende Ware transportf\u00e4hig zu verpacken. Besch\u00e4digte oder verlorene Ware, aufgrund einer nicht sachgem\u00e4ssen und nicht der Lieferung entsprechenden Verpackung, sowie der Aufwand zur Wiederherstellung der Ware, werden dem Kunden, bis zum vollen Rechnungsbetrag der Lieferung, verrechnet. \u00dcbergibt der Kunde die Ware einem Transportunternehmen, tr\u00e4gt der Kunde die Gefahr f\u00fcr den sicheren Transport der Ware. Der Gefahren\u00fcbergang an LIMODOR erfolgt erst mit dem Eingang der Ware bei LIMODOR.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-119985056\">\n\n\n\t<div id=\"col-190962818\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #14.-haftung\" data-bullet=\"false\" data-link=\"#14.-haftung\" data-title=\"14. Haftung\" ><a name=\"14.-haftung\"><\/a><\/span>\n\n<h4 id=\"AGB14\">14. Haftung<\/h4>\n<p>Schadenersatzanspr\u00fcche aus Unm\u00f6glichkeit der Leistung, aus Vertragsverletzung, aus Verschulden bei Vertragsschluss und aus unerlaubter Handlung, sind, soweit nicht vors\u00e4tzliches oder grobfahrl\u00e4ssiges Handeln vorliegt, ausgeschlossen. Die Haftung f\u00fcr indirekte Sch\u00e4den und Folgesch\u00e4den, die sich aus dem Gebrauch, durch Fehlleistung oder Leistungsausfall ergeben, ist ausgeschlossen.<\/p>\n<p>Eine R\u00fccknahme durch LIMODOR aufgrund besonderer Absprache ist ausschliesslich bis zwei Wochen (14 Kalendertage) nach Erhalt der Ware m\u00f6glich, massgebend ist das Datum der Zustellung bzw. Abholung. Der Kunde ist in jedem Fall daf\u00fcr verantwortlich, die zu retournierende Ware transportf\u00e4hig zu verpacken. Besch\u00e4digte oder verlorene Ware, aufgrund einer nicht sachgem\u00e4ssen und nicht der Lieferung entsprechenden Verpackung, sowie der Aufwand zur Wiederherstellung der Ware, werden dem Kunden, bis zum vollen Rechnungsbetrag der Lieferung, verrechnet. \u00dcbergibt der Kunde die Ware einem Transportunternehmen, tr\u00e4gt der Kunde die Gefahr f\u00fcr den sicheren Transport der Ware. Der Gefahren\u00fcbergang an LIMODOR erfolgt erst mit dem Eingang der Ware bei LIMODOR.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-1047270000\">\n\n\n\t<div id=\"col-351594252\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #15.-datenschutz\" data-bullet=\"false\" data-link=\"#15.-datenschutz\" data-title=\"15. Datenschutz\" ><a name=\"15.-datenschutz\"><\/a><\/span>\n\n<h4 id=\"AGB15\">15. Datenschutz<\/h4>\n<p>F\u00fcr die Bearbeitung von Personendaten durch LIMODOR gilt die Datenschutzerkl\u00e4rung von LIMODOR.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-304204974\">\n\n\n\t<div id=\"col-62764612\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #16.-gerichtsstand-und-anwendbares-recht\" data-bullet=\"false\" data-link=\"#16.-gerichtsstand-und-anwendbares-recht\" data-title=\"16. Gerichtsstand und anwendbares Recht\" ><a name=\"16.-gerichtsstand-und-anwendbares-recht\"><\/a><\/span>\n\n<h4 id=\"AGB16\">16. Gerichtsstand und anwendbares Recht<\/h4>\n<p>Appenzell ist ausschliesslich Gerichtsstand f\u00fcr alle sich aus dem Vertragsverh\u00e4ltnis unmittelbar oder mittelbar ergebenden Streitigkeiten.<\/p>\n<p>S\u00e4mtliche Rechtsbeziehungen zwischen LIMODOR und dem Kunden unterstehen dem Schweizer Recht.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row row-small\"  id=\"row-2111185529\">\n\n\n\t<div id=\"col-1226881761\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<span class=\"scroll-to\" data-label=\"Scroll to: #17.-schlussbestimmungen\" data-bullet=\"false\" data-link=\"#17.-schlussbestimmungen\" data-title=\"17. Schlussbestimmungen\" ><a name=\"17.-schlussbestimmungen\"><\/a><\/span>\n\n<h4 id=\"AGB17\">17. Schlussbestimmungen<\/h4>\n<p>Sollte eine Bestimmung dieser allgemeinen Gesch\u00e4ftsbedingungen unwirksam sein, so hat dies keinen Einfluss auf die Wirksamkeit der \u00fcbrigen Bestimmungen sowie der allgemeinen Gesch\u00e4ftsbedingungen insgesamt. Anstelle der unwirksamen Bestimmung gelten die einschl\u00e4gigen gesetzlichen Bestimmungen.<\/p>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-72","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Allgemeine Gesch\u00e4ftsbedingungen - LIMODOR<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Allgemeine Gesch\u00e4ftsbedingungen - LIMODOR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/\" \/>\n<meta property=\"og:site_name\" content=\"Limodor CH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T12:11:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"11\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/allgemeine_geschaeftsbedingungen\\\/\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/allgemeine_geschaeftsbedingungen\\\/\",\"name\":\"Allgemeine Gesch\u00e4ftsbedingungen - LIMODOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/#website\"},\"datePublished\":\"2023-08-25T12:16:59+00:00\",\"dateModified\":\"2024-09-09T12:11:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/allgemeine_geschaeftsbedingungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/allgemeine_geschaeftsbedingungen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/allgemeine_geschaeftsbedingungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Allgemeine Gesch\u00e4ftsbedingungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/#website\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/\",\"name\":\"Limodor CH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Allgemeine Gesch\u00e4ftsbedingungen - LIMODOR","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"de_DE","og_type":"article","og_title":"Allgemeine Gesch\u00e4ftsbedingungen - LIMODOR","og_url":"https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/","og_site_name":"Limodor CH","article_modified_time":"2024-09-09T12:11:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"11\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/","url":"https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/","name":"Allgemeine Gesch\u00e4ftsbedingungen - LIMODOR","isPartOf":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/#website"},"datePublished":"2023-08-25T12:16:59+00:00","dateModified":"2024-09-09T12:11:36+00:00","breadcrumb":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/allgemeine_geschaeftsbedingungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/limodor-dev.dev-web.at\/ch\/"},{"@type":"ListItem","position":2,"name":"Allgemeine Gesch\u00e4ftsbedingungen"}]},{"@type":"WebSite","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/#website","url":"https:\/\/limodor-dev.dev-web.at\/ch\/","name":"Limodor CH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/limodor-dev.dev-web.at\/ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/pages\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":5,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/pages\/72\/revisions"}],"predecessor-version":[{"id":7240,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/pages\/72\/revisions\/7240"}],"wp:attachment":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/media?parent=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}