{"id":7437,"date":"2024-11-14T10:00:08","date_gmt":"2024-11-14T09:00:08","guid":{"rendered":"https:\/\/www.limodor.com\/ch\/?p=7437"},"modified":"2024-11-14T10:02:47","modified_gmt":"2024-11-14T09:02:47","slug":"feiertagsgruesse-und-betriebsferienankuendigung","status":"publish","type":"post","link":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/","title":{"rendered":"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung"},"content":{"rendered":"\n\t<section class=\"section no-padding\" id=\"section_1480637491\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-395508648\">\n\n\n\t<div id=\"col-1918483717\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Feiertagsw\u00fcnsche und Mitteilung zu unseren Betriebsferien<\/h2>\n\n<div class=\"row align-middle\"  id=\"row-1848539991\">\n\n\n\t<div id=\"col-859642676\" class=\"col medium-3 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-643112594\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1333554015\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1020\" src=\"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-1024x1024.jpg 1024w, https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-300x300.jpg 300w, https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-150x150.jpg 150w, https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-768x768.jpg 768w, https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-247x247.jpg 247w, https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-510x510.jpg 510w, https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24-100x100.jpg 100w, https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24.jpg 1500w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1333554015 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<p>W\u00e4hrend das Jahr sich dem Ende zuneigt, m\u00f6chten wir die Gelegenheit nutzen, um allen f\u00fcr ihre Unterst\u00fctzung und Zusammenarbeit in diesem Jahr herzlich zu danken. Wir w\u00fcnschen Ihnen friedvolle und freudige Feiertage.<\/p>\n<p>Unser Unternehmen macht vom 23. Dezember 2024 bis zum 3. Januar 2025 Betriebsferien. Ab dem 6. Januar 2025 sind wir wieder voller Tatendrang f\u00fcr Sie da.<\/p>\n<p>Frohe Weihnachten und ein gl\u00fcckliches neues Jahr!<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1480637491 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir bedanken uns herzlich f\u00fcr Ihre Unterst\u00fctzung und m\u00f6chten Sie zugleich \u00fcber unsere bevorstehenden Betriebsferien informieren.<\/p>\n","protected":false},"author":10,"featured_media":7438,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[59],"tags":[],"class_list":["post-7437","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemeines"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung - LIMODOR<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung - LIMODOR\" \/>\n<meta property=\"og:description\" content=\"Wir bedanken uns herzlich f\u00fcr Ihre Unterst\u00fctzung und m\u00f6chten Sie zugleich \u00fcber unsere bevorstehenden Betriebsferien informieren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/\" \/>\n<meta property=\"og:site_name\" content=\"Limodor CH\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-14T09:00:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T09:02:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung\",\"datePublished\":\"2024-11-14T09:00:08+00:00\",\"dateModified\":\"2024-11-14T09:02:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/\"},\"wordCount\":115,\"image\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/Weihnacht24.jpg\",\"articleSection\":[\"Allgemeines\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/\",\"name\":\"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung - LIMODOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/Weihnacht24.jpg\",\"datePublished\":\"2024-11-14T09:00:08+00:00\",\"dateModified\":\"2024-11-14T09:02:47+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/Weihnacht24.jpg\",\"contentUrl\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/11\\\/Weihnacht24.jpg\",\"width\":1500,\"height\":1500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/2024\\\/11\\\/14\\\/feiertagsgruesse-und-betriebsferienankuendigung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/#website\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/\",\"name\":\"Limodor CH\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/ch\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung - LIMODOR","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung - LIMODOR","og_description":"Wir bedanken uns herzlich f\u00fcr Ihre Unterst\u00fctzung und m\u00f6chten Sie zugleich \u00fcber unsere bevorstehenden Betriebsferien informieren.","og_url":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/","og_site_name":"Limodor CH","article_published_time":"2024-11-14T09:00:08+00:00","article_modified_time":"2024-11-14T09:02:47+00:00","og_image":[{"width":1500,"height":1500,"url":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/#article","isPartOf":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/"},"author":{"name":"","@id":""},"headline":"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung","datePublished":"2024-11-14T09:00:08+00:00","dateModified":"2024-11-14T09:02:47+00:00","mainEntityOfPage":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/"},"wordCount":115,"image":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/#primaryimage"},"thumbnailUrl":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24.jpg","articleSection":["Allgemeines"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/","url":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/","name":"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung - LIMODOR","isPartOf":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/#primaryimage"},"image":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/#primaryimage"},"thumbnailUrl":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24.jpg","datePublished":"2024-11-14T09:00:08+00:00","dateModified":"2024-11-14T09:02:47+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/#primaryimage","url":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24.jpg","contentUrl":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-content\/uploads\/sites\/3\/2024\/11\/Weihnacht24.jpg","width":1500,"height":1500},{"@type":"BreadcrumbList","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/2024\/11\/14\/feiertagsgruesse-und-betriebsferienankuendigung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/limodor-dev.dev-web.at\/ch\/"},{"@type":"ListItem","position":2,"name":"Feiertagsgr\u00fcsse und Betriebsferienank\u00fcndigung"}]},{"@type":"WebSite","@id":"https:\/\/limodor-dev.dev-web.at\/ch\/#website","url":"https:\/\/limodor-dev.dev-web.at\/ch\/","name":"Limodor CH","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/limodor-dev.dev-web.at\/ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"","url":"https:\/\/limodor-dev.dev-web.at\/ch\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/posts\/7437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/comments?post=7437"}],"version-history":[{"count":3,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/posts\/7437\/revisions"}],"predecessor-version":[{"id":7441,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/posts\/7437\/revisions\/7441"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/media\/7438"}],"wp:attachment":[{"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/media?parent=7437"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/categories?post=7437"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/ch\/wp-json\/wp\/v2\/tags?post=7437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}