{"id":2290,"date":"2023-08-09T12:05:27","date_gmt":"2023-08-09T10:05:27","guid":{"rendered":"https:\/\/limodor.dev-web.at\/de\/loesungen\/wohnraeume\/fitness-wellness\/"},"modified":"2023-10-30T17:55:06","modified_gmt":"2023-10-30T16:55:06","slug":"fitness-wellness","status":"publish","type":"page","link":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/","title":{"rendered":"Fitness &amp; Wellness"},"content":{"rendered":"\n\t<section class=\"section wohnraum-header section-bottom-space\" id=\"section_1742717500\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-full-width\"  id=\"row-1655994820\">\n\n\n\t<div id=\"col-690511149\" class=\"col medium-12 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"breadcrumbs-row\"><div class=\"breadcrumbs-container\"><div class=\"breadcrumb-element\"><a href=\"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/\"><span>L\u00f6sungen<\/span><\/a><div>><\/div><\/div><div class=\"breadcrumb-element\"><a href=\"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/\"><span>Wohnr\u00e4ume<\/span><\/a><div>><\/div><\/div><div class=\"breadcrumb-element\"><a href=\"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/\"><span>Fitness &amp; Wellness<\/span><\/a><\/div><\/div><\/div>\n\n<h1>Fitness &amp; WelLness<\/h1>\n<h4 class=\"uppercase\">Entspannend daheim <br \/>\nWohlf\u00fchlklima inklusive<br \/>\n<\/h4>\n\t<div id=\"gap-1878559687\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1878559687 {\n  padding-top: 10px;\n}\n@media (min-width:550px) {\n  #gap-1878559687 {\n    padding-top: 10px;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\n<p>Eine Sauna oder Infrarotkabine. Oder ein paar Fitnessger\u00e4te. Oder eine gute Zeit mit Freuden im Kellerst\u00fcberl? Alles m\u00f6glich und immer \u00f6fter auch realisiert. Frische Luft und angenehmes Raumklima braucht die Entspannung nat\u00fcrlich auch. Die Herausforderung f\u00fcr die L\u00fcftung: Feuchtigkeit, Schwei\u00dfgeruch oder auch einmal Essens- oder Zigarettenrauch sollen, in den meistens im Untergescho\u00df befindlichen R\u00e4umen, nicht h\u00e4ngenbleiben. <\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-196980304\" class=\"col medium-12 small-12 large-6 medium-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover wave x md-x lg-x y md-y lg-y\" id=\"image_951932335\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:56.25%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1706\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1.jpg\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1.jpg 2560w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1-300x200.jpg 300w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1-1024x682.jpg 1024w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1-768x512.jpg 768w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1-1536x1024.jpg 1536w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1-2048x1365.jpg 2048w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Fitnessraum-scaled-1-510x340.jpg 510w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_951932335 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1742717500 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_2046710089\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-color:rgb(0, 105, 180);border-width:3px 0px 3px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse row-full-width align-center\"  id=\"row-1825731299\">\n\n\n\t<div id=\"col-2084858574\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h3>Vorteile<\/h3>\n<div class=\"icon-slider-container\"><div class=\"e5-slider-elements owl-carousel owl-theme\"><div class=\"e5-icon-container\"><div class=\"e5-icon-animation\"><div class=\"lottie-placeholder\" data-src=\"\/wp-content\/uploads\/2023\/08\/Beseitigung-von-Feuchtigkeit.json\"><\/div><\/div><div class=\"e5-icon-text\"><span>Wirksame Entfeuchtung<\/span><\/div><\/div><div class=\"e5-icon-container\"><div class=\"e5-icon-animation\"><div class=\"lottie-placeholder\" data-src=\"\/wp-content\/uploads\/2023\/08\/Aufwertung.json\"><\/div><\/div><div class=\"e5-icon-text\"><span>Rasche Absaugung schlechter Luft<\/span><\/div><\/div><div class=\"e5-icon-container\"><div class=\"e5-icon-animation\"><div class=\"lottie-placeholder\" data-src=\"\/wp-content\/uploads\/2023\/08\/Ideal.json\"><\/div><\/div><div class=\"e5-icon-text\"><span>Keine Zugluft<\/span><\/div><\/div><div class=\"e5-icon-container\"><div class=\"e5-icon-animation\"><div class=\"lottie-placeholder\" data-src=\"\/wp-content\/uploads\/2023\/08\/Schutz-vor-Schimmelbildung.json\"><\/div><\/div><div class=\"e5-icon-text\"><span>Wirksamer Schimmelschutz<\/span><\/div><\/div><\/div><div class=\"e5-slider-navigation\"><img decoding=\"async\" alt=\"Pfeil links\" class=\"arrow-left\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/mu-plugins\/limodor\/images\/right-arrow.svg\" \/><img decoding=\"async\" alt=\"Pfeil rechts\" class=\"arrow-right\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/mu-plugins\/limodor\/images\/right-arrow.svg\" \/><\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2046710089 {\n  padding-top: 40px;\n  padding-bottom: 40px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_1487286595\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-206721797\">\n\n\n\t<div id=\"col-1144299749\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"e5-accordion-container\"><div class=\"e5-accordion-category-container\"><h3 class=\"e5-accordion accordion-header single-category\" data-categories=\"Fitness &amp; Wellness\">FAQ zu Fitness- &amp;  Wellnessr\u00e4umen<\/h3><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorkoennen-auch-luefter-mit-waermerueckgewinnung-nachgeruestet-werden\" data-categories=\"B\u00fcro,Dezentrale Wohnrauml\u00fcftung,Fitness &amp; Wellness,Keller,Neubau,Renovierungen,Wohnr\u00e4ume\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">K\u00f6nnen auch L\u00fcfter mit W\u00e4rmer\u00fcckgewinnung nachger\u00fcstet werden?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Wenn die M\u00f6glichkeit einer geradlinigen direkten Verbindung nach au\u00dfen besteht \u2013 z.B. im Wohnbereich oder bei halb freiliegenden Kellerr\u00e4umen in Hanglage \u2013 dann k\u00f6nnen L\u00fcfter je nach konkreter Situation und wo es energietechnisch sinnvoll ist, mit verh\u00e4ltnism\u00e4\u00dfig geringem Aufwand durch kompakte <a href=\"\/?page_id=117\">Dezentrale Wohnrauml\u00fcftungssysteme<\/a> ersetzt werden. Diese besitzen eingebaute W\u00e4rmetauscher.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorwarum-sind-ein-steuergeraet-und-sensoren-fuer-eine-lueftung-von-kellerraeumen-sinnvoll\" data-categories=\"Fitness &amp; Wellness,Keller,Neubau,Renovierungen,Zentrall\u00fcftungssystem\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Warum sind ein Steuerger\u00e4t und Sensoren f\u00fcr eine L\u00fcftung von Kellerr\u00e4umen sinnvoll?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Eine wirksame Entfeuchtung funktioniert nur dann, wenn die Luftfeuchte drau\u00dfen geringer ist als drinnen. Das ist auch temperaturabh\u00e4ngig. Die Steuerung erkennt \u00fcber die Sensoren, wann optimale L\u00fcftungsbedingungen vorhanden sind. Nur dann aktiviert sie die L\u00fcftung. Fehlbel\u00fcftung mit warmer feuchter Luft von au\u00dfen wird verhindert.<\/p>\n<p>Oft sind in Kellerr\u00e4umen auch Waschk\u00fcche, W\u00e4schtrockenraum, Sauna oder Fitnessraum lokalisiert. Schwallartig entstehende Feuchtigkeit, etwa nach einem Saunagang oder nach Aufh\u00e4ngen einer Ladung nasser W\u00e4sche wird durch den Feuchtesensor erkannt und die L\u00fcftung f\u00fcr eine beschr\u00e4nkte Zeit auf Intensivstufe aktiviert, um die feuchte Luft m\u00f6glichst rasch aus dem Raum zu entfernen.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorwie-wird-ein-saunaraum-effizient-entlueftet\" data-categories=\"Abluftsystem,Abstellraum,Fitness &amp; Wellness,Keller,Neubau,Renovierungen,Wohnr\u00e4ume\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Wie wird ein Sauna- oder W\u00e4scheraum effizient entl\u00fcftet?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Mehrere Qualit\u00e4tsfaktoren z\u00e4hlen: Eine momentan anfallende gro\u00dfe Feuchtemenge muss m\u00f6glichst rasch und gleichzeitig ohne gro\u00dfen Energieverlust aus dem Raum ins Freie verfrachtet werden. Au\u00dferdem soll der Raum in der kalten Jahreszeit nicht stark abk\u00fchlen, um Kondensation zu verhindern. Das ben\u00f6tigt leistungsf\u00e4hige Abluftger\u00e4te, die automatisiert f\u00fcr kurze Zeit im Volllastbetreib laufen und dann entweder ausschalten oder in einem energieeffizienten Grundlastbetrieb laufen. Die L\u00fcftungsaktivierung erfolgt durch manuelles Ein-\/Ausschalten oder besser automatisch \u00fcber eine effiziente Feuchtesteuerung.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorbringt-eine-kellerlueftung-rasch-den-dampf-nach-einem-saunagang-aus-dem-raum\" data-categories=\"Fitness &amp; Wellness,Keller,Neubau,Renovierungen,Wohnr\u00e4ume,Zentrall\u00fcftungssystem\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Bringt eine Kellerl\u00fcftung rasch den Dampf nach einem Saunagang aus dem Raum?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Ja, die Steuerung erkennt eine momentan starke Feuchtbelastung und aktiviert die L\u00fcftung automatisch, welche den Dampf rasch und effizient ins Freie bringt. Gleichzeitig stellt sie aber sicher, dass im normalen Alltag nur dann gel\u00fcftet wird, wenn die Au\u00dfenluft trockener als die Kellerluft ist. das sorgt f\u00fcr optimales Kellerklima.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorgib-es-varianten-fuer-ein-und-mehrfamilienhaeuser\" data-categories=\"Fitness &amp; Wellness,Keller,Neubau,Renovierungen,Zentrall\u00fcftungssystem\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Gib es Kellerl\u00fcftungsvarianten f\u00fcr Ein \u2013 und Mehrfamilienh\u00e4user?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Ja, sowohl f\u00fcr Einfamilienh\u00e4user als auch f\u00fcr Wohnhausanlagen lassen sich individuelle Anlagen realisieren. Sie werden nach Gr\u00f6\u00dfe und Situation vor Ort individuell geplant. Bei gr\u00f6\u00dferen Objekten, wo die Kellerr\u00e4ume von vielen Bewohnern gemeinschaftlich genutzt werden, sind oft weitere Sensoren, zus\u00e4tzliche oder leistungsst\u00e4rkere L\u00fcftungselemente und andere Steuerungen sinnvoll. Kompakte Einfamilienhauskeller sind l\u00fcftungstechnisch individuell auf die jeweilige Nutzung durch die Hausbesitzer abgestimmt. Sie\u00a0 k\u00f6nnen, wo erw\u00fcnscht und sinnvoll, mit den restlichen R\u00e4umen des Hauses in ein gemeinsames L\u00fcftungskonzept integriert werden oder nach Bedarf z.B. mit einer Saunal\u00fcftung ausgestattet werden.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorwarum-sind-ein-steuergeraet-und-sensoren-fuer-die-lueftung-noetig\" data-categories=\"Abstellraum,Fitness &amp; Wellness,Keller,L\u00fcftungssysteme,Neubau,Renovierungen\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Warum sind ein Steuerger\u00e4t und Sensoren f\u00fcr die L\u00fcftung n\u00f6tig?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Eine wirksame Entfeuchtung funktioniert nur dann, wenn die Luftfeuchte drau\u00dfen geringer ist als drinnen. Die Steuerung erkennt \u00fcber kombinierte Temperatur- und Feuchtesensoren, wann optimale L\u00fcftungsbedingungen vorhanden sind. Nur dann aktiviert sie die L\u00fcftung. Fehlerhafte Bel\u00fcftung wird unterbunden. Ein weiteres wichtiges Kriterium sind die zunehmend in Kellern lokalisierten Wellness- oder Fitnessbereiche. In diesen entsteht typischerweise Feuchtigkeit, oft gro\u00dfe Mengen in kurzer Zeit wie beim Saunaausl\u00fcften. Diese muss zuverl\u00e4ssig erkannt und abgesaugt werden, idealerweise, ohne diese R\u00e4ume unangenehm abzuk\u00fchlen. Gleichzeitig wird auch unangenehmer Schwei\u00dfgeruch mit entfernt und die restlichen Abstell- und Lagerr\u00e4ume vor Schimmel und Kellermief gesch\u00fctzt. Die smarte Steuerung sorgt daf\u00fcr.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorwie-wird-ein-zentrallueftungssystem-gesteuert\" data-categories=\"Fitness &amp; Wellness,Keller,L\u00fcftungssysteme,Neubau,Renovierungen,Wohnr\u00e4ume,Zentrall\u00fcftungssystem\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Wie wird ein Zentrall\u00fcftungssystem gesteuert?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Die Steuerung einer Zentrall\u00fcftung hat je nach konkreter Ausf\u00fchrung verschiedene Funktionen. Beim air clean-System werden f\u00fcr den Grundlastbetrieb durch ein im Elektroschaltkasten angebrachtes Steuerelement die zentrale Frischluftzufuhr und mehrere dezentrale Abluftger\u00e4te wie die Limodor compact Einrohrl\u00fcfter optimal aufeinander abgestimmt geregelt. \u00dcber die Zentralsteuerung werden auch Bedarfsl\u00fcftung, Partybetrieb oder Sommerbetrieb eingestellt. Abluftelemente sind in jedem Raum zus\u00e4tzlich einzeln steuerbar. Sie k\u00f6nnen etwa im Bad mit einem Feuchtesensor oder auf der Toilette mittels Bewegungssensor f\u00fcr kurze Zeit von Grundlast auf Volllast geschaltet und so ihre jeweiligen L\u00fcftungsaufgabe rasch abarbeiten.<\/p>\n<p>Ein Spezialfall ist die LimDry Kellerl\u00fcftung: Hier erh\u00e4lt die Steuerung Messignale von Feuchtigkeits- und Temperatursensoren, die im Keller und im Au\u00dfenbereich lokalisiert sind. Abh\u00e4ngig von diesen Signalen wird bei optimalen Verh\u00e4ltnissen die Kellertrocknung aktiviert. Aber auch hier kann, beispielsweise beim Limodor ECom Einrohrl\u00fcftungssystem mit Feuchtemodul etwa der feuchte Luftschwall einer Sauna rasch mit voller Leistung abgesaugt werden. Schimmelbildung und Kellerfeuchtigkeit werden durch diese Kombination aus energiesparendem Grundlastbetreib und kurzfristiger Bedarfsl\u00fcftung bei Volllast optimal verhindert.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorwozu-brauche-ich-eine-kellerlueftung\" data-categories=\"Fitness &amp; Wellness,Keller,L\u00fcftungssysteme,Neubau,Renovierungen,Wohnr\u00e4ume,Zentrall\u00fcftungssystem\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Wozu brauche ich eine Kellerl\u00fcftung?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>In Zeiten knapper und teurer Wohnfl\u00e4chen r\u00fcckt der Keller als zus\u00e4tzliche Raumreserve immer \u00f6fter in den Fokus. Etwa f\u00fcrs Homeoffice, aber auch f\u00fcr eine Sauna oder einen Fitnessraum. Ein allseits bekanntes Problem auch in modernen H\u00e4usern: Speziell im Sommer bildet sich durch Kondensation feuchter warmer Au\u00dfenluft an den k\u00fchlen Kellerw\u00e4nden oft Schimmel oder Modergeruch. Einfaches L\u00fcften n\u00fctzt hier nichts, es versch\u00e4rft oft sogar die Situation.<\/p>\n<p>Das LimDry Kellerl\u00fcftungssystem arbeitet daher sensorgesteuert. Luftfeuchtigkeit und Temperatur innen und au\u00dfen werden gemessen. Ein smartes Steuerger\u00e4t stellt sicher, dass nur trockene Au\u00dfenluft ins Haus gelangt. Feuchte oder geruchsbelastete Innenluft wird abgesaugt. Das sorgt f\u00fcr optimale Kellertrocknung. Auch eine Saunal\u00fcftung kann integriert werden. Schimmelschutz ist so gew\u00e4hrleistet, volle Flexibilit\u00e4t bei Auslegung und Betrieb analog einer Wohnrauml\u00fcftung ebenso.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorwo-und-wie-werden-abluftsysteme-montiert\" data-categories=\"Abluftsystem,Abstellraum,Badezimmer,Fitness &amp; Wellness,Garage,L\u00fcftungssysteme,Neubau,Renovierungen,WC,Wohnr\u00e4ume\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Wo und wie werden Abluftsysteme montiert?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Je nachdem, ob Axialventilator, Radialventilator oder Einrohrl\u00fcfter, sind die Montagem\u00f6glichkeiten variabel. Axialventilatoren wie der Limax sind typischerweise in geraden kurze Rohren eingebaut, z.B. bei einer Bad- oder Toilettenl\u00fcftung, die direkt durch die Au\u00dfenwand f\u00fchren. Radialventilatoren werden ebenfalls direkt in den Rohrstrang eingebaut und sind auch f\u00fcr l\u00e4ngere Leitungen geeignet. Je nach baulicher Situation m\u00fcssen aber Brandschutzelemente separat eingebaut werden.<\/p>\n<p>Am flexibelsten ist das Limodor-Einrohl\u00fcftungssystem. Die L\u00fcfter k\u00f6nnen als Unterputz- und Aufputzvariante, in und auf W\u00e4nden oder an der Decke verbaut werden. Sie decken alle Einsatzbereiche im Haus ab und arbeiten auch als Zentralabsaugung am Dachboden, als Einzell\u00fcfter, Gruppen oder in Kombination mit anderen L\u00fcftungselementen.<\/p>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorluftstrom-richtig-steuern\" data-categories=\"Abluftsystem,Fitness &amp; Wellness,L\u00fcftungssysteme,Neubau,Renovierungen,Wohnr\u00e4ume\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Was muss bei der Luftstromf\u00fchrung ber\u00fccksichtigt werden?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>F\u00fcr einen effizienten Luftaustausch sollten einige Faktoren bedacht werden:<\/p>\n<ul>\n<li>Die Position des L\u00fcfters, z.B. in Bad oder WC, sollte so nahe wie m\u00f6glich am Entstehungsort der feuchten oder geruchsbelasteten Luft gew\u00e4hlt werden. Das steigert Effizienz und Schnelligkeit.<\/li>\n<li>L\u00fcfter nicht in toten Winkeln oder Bereichen montieren, wo der angesaugte Luftstrom auf Hindernisse trifft.<\/li>\n<li>Auch nachstr\u00f6mende Luft, z.B. durch T\u00fcren oder Zuluftelemente sollte m\u00f6glichst ungest\u00f6rt Richtung Absaugger\u00e4t streichen k\u00f6nnen, um speziell im Bad ein Maximum an Feuchtigkeit aufnehmen zu k\u00f6nnen.<\/li>\n<li>In Zeiten immer dichterer R\u00e4ume und T\u00fcren muss bei Feuerstellen unbedingt ausreichend Zuluft, wenn n\u00f6tig durch eigene Zuluftelemente, sichergestellt werden, um kein giftiges Kohlenmonoxid\u00a0 zu erzeugen.<\/li>\n<li>Abgesaugte Luft sollte auf m\u00f6glichst kurzem und geradem Weg nach drau\u00dfen gelangen k\u00f6nnen. Jeder Knick oder jede Verengung senkt den Wirkungsgrad.<\/li>\n<li>Nat\u00fcrlich darf durch die L\u00fcfteranordnung auch keine unangenehme Zugluft entstehen.<\/li>\n<\/ul>\n<\/div><\/div><div class=\"e5-accordion e5-accordion-article\" id=\"e5Anchorfrage-zum-zuluftsystem\" data-categories=\"Fitness &amp; Wellness,L\u00fcftungssysteme\"><a href=\"#\" class=\"details-link accent\"><div class=\"e5-accordion-title-container\"><span class=\"e5-accordion-title\">Brauchen Zuluftsysteme einen Motor?<\/span><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"20\" height=\"17\" class=\"polygon\" viewBox=\"0 0 20 17\"><path id=\"Polygon_6\" data-name=\"Polygon 6\" d=\"M9.138,1.465a1,1,0,0,1,1.724,0l8.252,14.028A1,1,0,0,1,18.252,17H1.748a1,1,0,0,1-.862-1.507Z\" transform=\"translate(20 17) rotate(180)\" fill=\"#0069b4\"\/><\/svg><\/div><\/a><div class=\"row dropdown-content\"><p>Zuluftsysteme vom Typ AirOnova, die Limodor im Produktprogramm anbietet, sind rein passive Elemente. Sie ersetzen in moderner Form fr\u00fcher oft vorhandene T\u00fcrritze, undichte Fenster oder andere Luftzug\u00e4nge ins Haus. Und nat\u00fcrlich entf\u00e4llt dann Fenster\u00f6ffnen zum L\u00fcften. Zuluftelemente bieten durch einen Filterinsatz Schutz vor l\u00e4stigen Insekten, Staub und Allergenen. Besonders wichtig ist der L\u00e4rmschutz, der durch integrierte Schalld\u00e4mpfer erzielt wird. Au\u00dferdem kann die Luftzufuhr stufenlos verstellt werden. Pl\u00f6tzliche Windb\u00f6en f\u00e4ngt eine optionale Winddrucksicherung ab.<\/p>\n<p>Definiert man den Begriff Zuluftsystem etwas breiter, dann kann nat\u00fcrlich auch ein motorisierter Einrohrl\u00fcfter, etwa der Typ Limodor W, welcher auch als Ventilatorbox bezeichnet wird oder ein Dezentrales Wohnrauml\u00fcftungssystem wie der kompakte AirOdor zu Frischluftversorgung eingesetzt werden. Bei Wohnbl\u00f6cken mit Kellerl\u00fcftung wird beispielsweise oft eine Ventilatorbox zur Ansaugung und Verteilung von Frischluft integriert.<\/p>\n<\/div><\/div><\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1487286595 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section section-top-space\" id=\"section_895935176\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-308126342\">\n\n\n\t<div id=\"col-855483539\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n<h2>Unsere Abluftsysteme<\/h2>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_895935176 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section\" id=\"section_36009355\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-660315098\">\n\n\n\t<div id=\"col-546466075\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-502722339\">\n\n\n\t<div id=\"col-1352641362\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"color: #000000\"><strong><span style=\"font-size: 21.5pt\">LIMODOR AirVital<\/span><\/strong><\/span><\/p>\n<p>Der Wandl\u00fcfter AirVital ist f\u00fcr die Be- und Entl\u00fcftung von einzelnen R\u00e4umen in Wohnungen (z.B. Schlaf-\/Wohn-\/ oder Kinderzimmer) geeignet. Der Einsatz eines Pollenfilters erh\u00f6ht insbesondere f\u00fcr Allergiker die Lebensqualit\u00e4t. Ein integrierter W\u00e4rmetauscher mindert weiterhin die Heizkosten. Der Luftvolumenstrom ist \u00fcber eine Fernbedienung oder direkt \u00fcber ein Display am AirVital stufenweise einstellbar.<\/p>\n<p><span style=\"color: #000000\"><strong>Kurzbeschreibung:<\/strong><\/span><b><br \/><\/b>\u2022 Montageort: Au\u00dfenwand<br \/>\u2022 Versorgungsspannung: 230 VDC\/50Hz<br \/>\u2022 Volumenstrom: 25..35..60 m3\/h (regelbar)<br \/>\u2022 W\u00e4rmebereitstellungsgrad max: 57 %<br \/>\u2022 Filterklasse Zu-\/Abluft: ePM1&gt;50%ISO Coars &gt;45% (F7\/G3)<br \/>\u2022 Eingangsleistung (mittel): &lt; 0,52 W\/m3\/h<br \/>\u2022 Wandst\u00e4rke: 60 bis 395 (895) mm<\/p>\n<a href=\"\/de\/loesungen\/lueftungssysteme\/wandluefter-dezentral\/airvital\/\" target=\"_self\" class=\"button primary is-outline\"  style=\"border-radius:10px;\">\n    <span>Weitere Informationen<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-811609214\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_755627185\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"816\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVital_Inhaltsseite_Komplettgeraet-1024x819.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVital_Inhaltsseite_Komplettgeraet-1024x819.jpg 1024w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVital_Inhaltsseite_Komplettgeraet-300x240.jpg 300w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVital_Inhaltsseite_Komplettgeraet-768x614.jpg 768w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVital_Inhaltsseite_Komplettgeraet-1536x1229.jpg 1536w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVital_Inhaltsseite_Komplettgeraet-510x408.jpg 510w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVital_Inhaltsseite_Komplettgeraet.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_755627185 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_36009355 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1176369256\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-340773628\">\n\n\n\t<div id=\"col-909809164\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-1510199329\">\n\n\n\t<div id=\"col-393768745\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"color: #000000\"><strong><span style=\"font-size: 21.5pt\">LIMODOR AirVital Prime<\/span><\/strong><\/span><\/p>\n<p>Der Wandl\u00fcfter Serie AirVital Prime erm\u00f6glicht einen stetigen Zu-\/Abluftbetrieb mit W\u00e4rme\u00fcbertragung inklusive Filterung der Zu-\/Abluft (Standard: ePM10&gt;50% &gt;45% -alt M5-). Einsetzbar f\u00fcr einen Luftaustausch z.B. in einem Wohnraum bzw. zur Entl\u00fcftung einer Wohnung (Nutzereinheit). Die W\u00e4rme\u00fcbertragung wird mittels Kreuz-Gegenstrom-W\u00e4rme\u00fcbetrager aus Kunststoff realisiert und erm\u00f6glicht eine hocheffiziente W\u00e4rme\u00fcbertragung von bis zu 94 %. Die Fort- und Au\u00dfenluftf\u00fchrung erfolgt \u00fcber zwei getrennte Rohre. Serienm\u00e4\u00dfig besitzt der AirVital Prime eine automatische Kondensatentleerung und Luftklappenansteuerung bei Ger\u00e4testillstand.<\/p>\n<p><span style=\"color: #000000\"><strong>Kurzbeschreibung:<\/strong><\/span><b><br \/><\/b>\u2022 Montageort: Au\u00dfenwand<br \/>\u2022 Versorgungsspannung: 230 VDC\/50Hz<br \/>\u2022 Volumenstrom: 10 bis 45 (60) m3\/h (regelbar)<br \/>\u2022 W\u00e4rmebereitstellungsgrad max: 71 %<br \/>\u2022 Filterklasse Zu-\/Abluft: ePM10&gt;50% (M5)<br \/>\u2022 Eingangsleistung (mittel): &lt; 0,27 W\/m3\/h<br \/>\u2022 Wandst\u00e4rke: 360 bis 790 mm<\/p>\n<a href=\"\/de\/loesungen\/lueftungssysteme\/wandluefter-dezentral\/airvital-prime\/\" target=\"_self\" class=\"button primary is-outline\"  style=\"border-radius:10px;\">\n    <span>Weitere Informationen<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-660714912\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_438891616\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"816\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVitalPrime_Inhaltsseite_Komplettgeraet-1024x819.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVitalPrime_Inhaltsseite_Komplettgeraet-1024x819.jpg 1024w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVitalPrime_Inhaltsseite_Komplettgeraet-300x240.jpg 300w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVitalPrime_Inhaltsseite_Komplettgeraet-768x614.jpg 768w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVitalPrime_Inhaltsseite_Komplettgeraet-1536x1229.jpg 1536w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVitalPrime_Inhaltsseite_Komplettgeraet-2048x1638.jpg 2048w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/AirVitalPrime_Inhaltsseite_Komplettgeraet-510x408.jpg 510w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_438891616 {\n  width: 80%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1176369256 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_113851035\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-995445579\">\n\n\n\t<div id=\"col-1102880351\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-1950120523\">\n\n\n\t<div id=\"col-518966624\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<p><span style=\"color: #000000\"><strong><span style=\"font-size: 21.5pt\">LIMODOR Serie ECom<\/span><\/strong><\/span><\/p>\n<p>Unterputz-L\u00fcftungsger\u00e4t mit 2-stufiger EC-Motortechnik f\u00fcr den Einsatz z.B. in K\u00fcchen, Kochnischen, B\u00e4der oder WC's. Standardm\u00e4\u00dfig besitzt die L\u00fcfterserie ECom immer eine codierbare Nachlauf, Einschalt- und Intervallzeit und eine Filterkontrollanzeige. Der modulare Aufbau der L\u00fcfterserie erm\u00f6glicht die Vewendung zahlreicher weiterer Steuermodule (z.B. Nachlauf, Feuchte, Bewegung, ....). Die federbelastete R\u00fcckschlagklappe im Einbaukasten verhindert eine Geruchs- und (Kalt)Rauch\u00fcbertragung -Leckluftrate &lt; 0,01 m\u00b3\/h-.<\/p>\n<p><span style=\"color: #000000\"><strong>Kurzbeschreibung:<\/strong><\/span><br \/>\u2022 Montageart: Unterputz<br \/>\u2022 Montageort: Wand\/Decke<br \/>\u2022 Motorausf\u00fchrung: 2-stufig (3-stufig mit EC-INR)<br \/>\u2022 Volllast: 30, 40, 60 und 100 m3\/h (codierbar)<br \/>\u2022 Teillast: 15, 20, 30 und 40 m3\/h (codierbar)<br \/>\u2022 Anschlussstutzen: DN80, seitlich<\/p>\n<p><span style=\"color: #000000\"><strong>Ausf\u00fchrungsvarianten:<\/strong><\/span><br \/>\u2022 -BR (mit Brandschutz)<br \/>\u2022 -K (wie BR + aktiver Absperrklappe)<\/p>\n<a href=\"\/de\/loesungen\/lueftungssysteme\/abluftgeraete\/limodor-ecom\/\" target=\"_self\" class=\"button primary is-outline\"  >\n    <span>Weitere Informationen<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-497362334\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_759461343\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1020\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt-1024x1024.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt-1024x1024.png 1024w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt-300x300.png 300w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt-150x150.png 150w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt-768x768.png 768w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt-600x600.png 600w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt-100x100.png 100w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/ECom_Luefter_Produkt.png 1181w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_759461343 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_113851035 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_504143049\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\r\n\r\n<div class=\"row\"  id=\"row-597243111\">\r\n\r\n\n\t<div id=\"col-2057432842\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<div class=\"row align-middle align-center\"  id=\"row-713934803\">\r\n\r\n\n\t<div id=\"col-1998670801\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\r\n\r\n<p><span style=\"color: #000000\"><strong><span style=\"font-size: 21.5pt\">LIMODOR Serie compact<\/span><\/strong><\/span><\/p>\r\n<p>Unterputz-L\u00fcftungsger\u00e4t mit AC-Motortechnik (Volumenstrom durch Auswahl Motorelektronik -Leistungsteil-\u00a0 w\u00e4hlbar z.B. 60\/30 m\u00b3\/h) f\u00fcr den Einsatz z.B. in K\u00fcchen, Kochnischen, B\u00e4der oder WC\u2019s. Auswahl von codierbaren Nachlauf, Einschalt- und Intervallzeit oder auch automatischer Feuchtebetrieb durch zahlreiche weiterer Steuermodule m\u00f6glich. Die federbelastete R\u00fcckschlagklappe im Einbaukasten verhindert eine Geruchs- und (Kalt)Rauch\u00fcbertragung -Leckluftrate &lt; 0,01 m\u00b3\/h-.<\/p>\r\n<p><span style=\"color: #000000\"><strong>Kurzbeschreibung:<\/strong><\/span><br \/>\u2022 Montageart: Unterputz<br \/>\u2022 Montageort: Wand\/Decke<br \/>\u2022 Motorausf\u00fchrung: 1, 2 oder 3-stufig<br \/>\u2022 Volumenstrom Volllast: 45, 60 und 100 m3\/h (w\u00e4hlbar)<br \/>\u2022 Volumemstrom Teillast: 25, 30 und 40 m3\/h (zugeordnet)<br \/>\u2022 Volumemstrom 3-stufig: 100-60-30 m3\/h<br \/>\u2022 Anschlussstutzen: DN80, seitlich<\/p>\r\n<p><span style=\"color: #000000\"><strong>Ausf\u00fchrungsvarianten:<\/strong><\/span><br \/>\u2022 -BR (mit Brandschutz)<br \/>\u2022 -K (wie BR + aktiver Absperrklappe)<\/p>\r\n<a href=\"\/de\/loesungen\/lueftungssysteme\/abluftgeraete\/limodor-compact\/\" target=\"_self\" class=\"button primary is-outline\"  style=\"border-radius:10px;\">\n    <span>Weitere Informationen<\/span>\n  <\/a>\n\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\n\t<div id=\"col-1350103441\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner text-center\"  >\n\t\t\t\n\t\t\t\r\n\r\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_594010018\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"1020\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-1024x1024.jpg 1024w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-300x300.jpg 300w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-150x150.jpg 150w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-768x768.jpg 768w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-1536x1536.jpg 1536w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-600x600.jpg 600w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet-100x100.jpg 100w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/09\/LimodorFM_Inhaltsseite_Komplettgeraet.jpg 2000w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_594010018 {\n  width: 60%;\n}\n<\/style>\n\t<\/div>\n\t\r\n\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\r\n\r\n<\/div>\r\n\r\n\t\t<\/div>\n\n\t\t\n<style>\n#section_504143049 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1031200746\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row row-collapse align-middle align-right ventilation-system-overview\"  id=\"row-141582176\">\n\n\n\t<div id=\"col-1932450209\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-1169056453\" class=\"text\">\n\t\t\n\n<p class=\"sub-headline\">Nicht das Richtige gefunden?<\/p>\n\t\t\n<style>\n#text-1169056453 {\n  text-align: right;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-46644114\" class=\"col medium-6 small-12 large-3\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"\/de\/wohnraeume\" target=\"_self\" class=\"button primary is-outline is-small\"  style=\"border-radius:10px;\">\n    <span>zur\u00fcck zur \u00dcbersicht<\/span>\n  <\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-46644114 > .col-inner {\n  padding: 0px 0px 0px 30px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1031200746 {\n  padding-top: 40px;\n  padding-bottom: 40px;\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":300,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-2290","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fitness &amp; Wellness - LIMODOR<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fitness &amp; Wellness - LIMODOR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/\" \/>\n<meta property=\"og:site_name\" content=\"LIMODOR DE\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-30T16:55:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/lueftungen\\\/wohnraeume\\\/fitness-wellness\\\/\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/lueftungen\\\/wohnraeume\\\/fitness-wellness\\\/\",\"name\":\"Fitness &amp; Wellness - LIMODOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/#website\"},\"datePublished\":\"2023-08-09T10:05:27+00:00\",\"dateModified\":\"2023-10-30T16:55:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/lueftungen\\\/wohnraeume\\\/fitness-wellness\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/lueftungen\\\/wohnraeume\\\/fitness-wellness\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/lueftungen\\\/wohnraeume\\\/fitness-wellness\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f6sungen\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/lueftungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Wohnr\u00e4ume\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/lueftungen\\\/wohnraeume\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Fitness &amp; Wellness\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/\",\"name\":\"LIMODOR DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fitness &amp; Wellness - LIMODOR","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Fitness &amp; Wellness - LIMODOR","og_url":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/","og_site_name":"LIMODOR DE","article_modified_time":"2023-10-30T16:55:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/","url":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/","name":"Fitness &amp; Wellness - LIMODOR","isPartOf":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/#website"},"datePublished":"2023-08-09T10:05:27+00:00","dateModified":"2023-10-30T16:55:06+00:00","breadcrumb":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/fitness-wellness\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/limodor-dev.dev-web.at\/de\/"},{"@type":"ListItem","position":2,"name":"L\u00f6sungen","item":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/"},{"@type":"ListItem","position":3,"name":"Wohnr\u00e4ume","item":"https:\/\/limodor-dev.dev-web.at\/de\/lueftungen\/wohnraeume\/"},{"@type":"ListItem","position":4,"name":"Fitness &amp; Wellness"}]},{"@type":"WebSite","@id":"https:\/\/limodor-dev.dev-web.at\/de\/#website","url":"https:\/\/limodor-dev.dev-web.at\/de\/","name":"LIMODOR DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/limodor-dev.dev-web.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/pages\/2290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/comments?post=2290"}],"version-history":[{"count":1,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/pages\/2290\/revisions"}],"predecessor-version":[{"id":7456,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/pages\/2290\/revisions\/7456"}],"up":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/pages\/300"}],"wp:attachment":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/media?parent=2290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}