{"id":2699,"date":"2023-10-10T12:57:09","date_gmt":"2023-10-10T10:57:09","guid":{"rendered":"https:\/\/limodor.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/"},"modified":"2023-11-06T09:46:42","modified_gmt":"2023-11-06T08:46:42","slug":"husten-oder-durchatmen-passende-feuchte","status":"publish","type":"post","link":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/","title":{"rendered":"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit"},"content":{"rendered":"\n\t<section class=\"section no-padding\" id=\"section_1830222300\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-394831065\">\n\n\n\t<div id=\"col-148318323\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h2>Hustest du noch oder atmest du schon&nbsp; durch?&nbsp;<\/h2>\n<h4>Wohlf\u00fchlfaktor Luftfeuchtigkeit<\/h4>\n<p>Auch wenn der 2023 bislang extrem warme Herbst es noch nicht wirklich vermittelt: Die Stresszeit f\u00fcr die Atmungsorgane steht wieder bevor, wenn wir uns vermehrt in Innenr\u00e4umen aufhalten: Insbesondere Temperatur und Luftfeuchtigkeit, aber auch die Luftqualit\u00e4t bestimmen dort das Raumklima. Belastete Atemluft reduziert die Leistungsf\u00e4higkeit: Brennende Augen, trockene Schleimh\u00e4ute, anhaltende M\u00fcdigkeit trotz ausreichendem Schlaf, Kopfschmerzen oder Konzentrationsschw\u00e4che sind untr\u00fcgliche Anzeichen f\u00fcr ein schlechtes Wohnklima. Von den \u00fcber geschw\u00e4chten Organismus kombiniert mit idealen Vermehrungsbedingungen jubelnden Grippe- und Coronaviren ganz zu schweigen.<\/p>\n<p>Deshalb sind L\u00fcften und der kontinuierliche Austausch belasteter Raumluft durch frischer Luft so wichtig. Unsere herbstliche Miniserie erkl\u00e4rt, worauf es darauf ankommt. Im aktuellen Beitrag geht es um Know-how rund um die optimale Feuchtigkeit.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1830222300 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section no-padding\" id=\"section_1126065388\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-294505906\">\n\n\n\t<div id=\"col-1890395333\" class=\"col no-padding-bottom medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>50%: Nicht zu trocken, nicht zu nass<\/strong><\/h3>\n<p>Zu hohe Luftfeuchtigkeit empfinden wir als dr\u00fcckend. Zudem ist sie hygienisch keimanf\u00e4lliger als niedrige. Empfehlenswert ist eine Raumluftfeuchte von 40\u201360 % in Wohn- und Schlafr\u00e4umen. Dar\u00fcber liegende Werte f\u00f6rdern das Wachstum von Milben, bei \u00fcber 70% auch von Schimmel. Tapeten l\u00f6sen sich ab, Inneneinrichtungen und Bausubstanz werden gesch\u00e4digt. Augen, Haut und Atemwege sind gereizt, Allergien treten auf. Leicht k\u00f6nnen daraus chronische Erkrankungen wie Husten oder Asthma entstehen.<\/p>\n<h5>Sommer: Warme Luft speichert Feuchte<\/h5>\n<p>Bei einer Raumtemperatur von 20 \u00b0C kann ein Kubikmeter Luft rund 17 Gramm&nbsp; Wasserdampf aufnehmen, bei 10 \u00b0C nur noch halb soviel. W\u00e4hrend des warmen Sommers ist die Raumluft daher besonders feucht. Duschen, Kochen oder nasse W\u00e4sche lassen den Dampfgehalt rasch ansteigen, der sich dann an kalten Fl\u00e4chen wie Ecken oder Fensterscheiben als Tauwasser niederschl\u00e4gt. Besonders in Kellern ist die Gefahr hoch, dass bei falschem L\u00fcften auch warme feuchte Au\u00dfenluft ins Untergescho\u00df absinkt und an den k\u00fchlen W\u00e4nden kondensiert.<\/p>\n<h5>Winter: Meist zu trockenes Raumklima<\/h5>\n<p>In den Wintermonaten ist die Raumluft eher zu trocken, da trockene Au\u00dfenluft auf trockene Heizungsluft trifft. Je h\u00f6her die Raumtemperatur ist, desto trockener die Luft. Ein Plus von drei Grad reduziert die relative Feuchte um mehr als sechs Prozent. Zu geringe Luftfeuchtigkeit f\u00fchrt h\u00e4ufig zu Kopfschmerzen und reizt die Atemwege. Die Schleimh\u00e4ute trocknen aus und werden anf\u00e4llig f\u00fcr Bakterien\u00ad und\u00ad Viren.<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-584835645\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2094168015\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:200%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-23-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-23-1024x683.jpg 1024w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-23-300x200.jpg 300w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-23-768x512.jpg 768w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-23-1536x1024.jpg 1536w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-23-2048x1366.jpg 2048w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-23-510x340.jpg 510w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2094168015 {\n  width: 96%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1502174810\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-158968427\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-158968427 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3><strong>L\u00fcftungstipps f\u00fcr angenehmes Luftfeuchteempfinden:<\/strong><\/h3>\n<ul>\n<li>Ein um wenig Geld erh\u00e4ltliches Hygrometer bietet rasche Information zur aktuellen Raumfeuchte.<\/li>\n<li>Beim L\u00fcften sollte der Luftstromvon der Zuluftseite direkt \u00fcber den Bereich der Feuchtigkeitsentstehung (nasse W\u00e4sche, Dusche, ge\u00f6ffnete Sauna etc.) in Richtung des offenen Fensters streichen. Damit wird die Feuchte gut aufgenommen und abtransportiert.<\/li>\n<li>Besonders im Sommer das L\u00fcften soweit m\u00f6glich auf Morgen-, Abend- und Nachtstunden verschieben, da dann der Feuchtegehalt der Au\u00dfenluft geringer ist.<\/li>\n<li>In der kalten Jahreszeit f\u00fcr Raumbefeuchtung (Verdunster, Zierbrunnen etc.) sorgen.<\/li>\n<li>In der Heizsaison wirkt sich ausnahmsweise auch ein St\u00e4nder, auf dem z.B. tags\u00fcber W\u00e4sche trocknet, durch deren Feuchteabgabe positiv auf das Raumklima aus.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1332959143\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1332959143 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1126065388 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\t<section class=\"section no-padding\" id=\"section_1232849565\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-976161405\">\n\n\n\t<div id=\"col-2020216013\" class=\"col no-padding-bottom medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>So helfen L\u00fcftungssysteme:<\/strong><\/h3>\n<ul>\n<li><a href=\"\/de\/lueftungen\/lueftungssysteme\/zentrallueftungssystem\/\">Zentrall\u00fcftungssysteme<\/a> sorgen \u00fcber Feuchtigkeitssensoren automatisch f\u00fcr Frischluftzufuhr, wenn der Feuchtegehalt zu hoch wird.<\/li>\n<li><a href=\"\/de\/lueftungen\/lueftungssysteme\/zentrallueftungssystem\/kellerlueftung\/\">Kellerl\u00fcftungssysteme<\/a> messen Innen- und Au\u00dfenfeuchte, optimieren die L\u00fcftungszyklen und verhindern Fehlbel\u00fcftungen durch Ansaugen feuchter Au\u00dfenluft.<\/li>\n<li><a href=\"\/de\/lueftungen\/lueftungssysteme\/abluftgeraete\/\" data-wplink-edit=\"true\">Abluftsysteme<\/a> wie z.B. Bad- oder Sauanal\u00fcfter mit Feuchtesensoren saugen bereits w\u00e4hrend der Entstehung Dampf ab und sorgen so durch ihre automatische Steuerung in nur wenigen Minuten effizient f\u00fcr wieder trockene R\u00e4ume. Sie k\u00f6nnen unmittelbar im Umfeld der Feuchtequellen angebracht werden.<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1464849337\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_604086401\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:100%;\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-11_Hochformat-768x1024.jpg\" class=\"attachment-medium_large size-medium_large\" alt=\"\" srcset=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-11_Hochformat-768x1024.jpg 768w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-11_Hochformat-225x300.jpg 225w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-11_Hochformat-1152x1536.jpg 1152w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-11_Hochformat-1536x2048.jpg 1536w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-11_Hochformat-510x680.jpg 510w, https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/20230928-Homepage-Bilder-Limodor-11_Hochformat-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_604086401 {\n  width: 82%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1123809194\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h3><strong>Gewusst?<\/strong><\/h3>\n<p>Ein Bad nach dem Duschen durch Fenster\u00f6ffnen zu trocknen, funktioniert meist nur schlecht. Die Feuchte schl\u00e4gt sich oft bereits zuvor nieder und kondensiert durch eindringende k\u00fchlere Luft noch schneller an W\u00e4nden und Spiegel. Au\u00dferdem entsteht der Dampf meist dort, wo sich kein Fenster befindet. Das Bad k\u00fchlt ab und muss neu erw\u00e4rmt werden &#8211; Energieverschwendung pur! Ein moderner LIMODOR -L\u00fcfter trocknet ein Bad hingegen automatisch gesteuert und ohne l\u00e4stige Zugluft mit minimalem Strombedarf in nur 20 Minuten. Der Raum bleibt durch nachstr\u00f6mende Luft aus dem Wohnbereich wohlig warm.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-956455953\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-956455953 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-1973540731\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1973540731 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1232849565 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"<p>Zu hohe Luftfeuchtigkeit empfinden wir als dr\u00fcckend. Zudem ist sie hygienisch<\/p>\n","protected":false},"author":8,"featured_media":2700,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[60],"tags":[],"class_list":["post-2699","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tipps"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit - LIMODOR<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit - LIMODOR\" \/>\n<meta property=\"og:description\" content=\"Zu hohe Luftfeuchtigkeit empfinden wir als dr\u00fcckend. Zudem ist sie hygienisch\" \/>\n<meta property=\"og:url\" content=\"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/\" \/>\n<meta property=\"og:site_name\" content=\"LIMODOR DE\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-10T10:57:09+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-06T08:46:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Hygrometer-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit\",\"datePublished\":\"2023-10-10T10:57:09+00:00\",\"dateModified\":\"2023-11-06T08:46:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/\"},\"wordCount\":788,\"image\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/Hygrometer-scaled.jpg\",\"articleSection\":[\"Tipps\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/\",\"name\":\"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit - LIMODOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/Hygrometer-scaled.jpg\",\"datePublished\":\"2023-10-10T10:57:09+00:00\",\"dateModified\":\"2023-11-06T08:46:42+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/Hygrometer-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2023\\\/10\\\/Hygrometer-scaled.jpg\",\"width\":2560,\"height\":1920,\"caption\":\"Was braucht gutes Raumklima in der Husten- und Schnupfenzeit? In Unserer Miniserie kl\u00e4rt auf.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/2023\\\/10\\\/10\\\/husten-oder-durchatmen-passende-feuchte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/\",\"name\":\"LIMODOR DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/author\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit - LIMODOR","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit - LIMODOR","og_description":"Zu hohe Luftfeuchtigkeit empfinden wir als dr\u00fcckend. Zudem ist sie hygienisch","og_url":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/","og_site_name":"LIMODOR DE","article_published_time":"2023-10-10T10:57:09+00:00","article_modified_time":"2023-11-06T08:46:42+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Hygrometer-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/#article","isPartOf":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/"},"author":{"name":"","@id":""},"headline":"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit","datePublished":"2023-10-10T10:57:09+00:00","dateModified":"2023-11-06T08:46:42+00:00","mainEntityOfPage":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/"},"wordCount":788,"image":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/#primaryimage"},"thumbnailUrl":"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Hygrometer-scaled.jpg","articleSection":["Tipps"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/","url":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/","name":"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit - LIMODOR","isPartOf":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/#primaryimage"},"image":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/#primaryimage"},"thumbnailUrl":"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Hygrometer-scaled.jpg","datePublished":"2023-10-10T10:57:09+00:00","dateModified":"2023-11-06T08:46:42+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/#primaryimage","url":"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Hygrometer-scaled.jpg","contentUrl":"https:\/\/limodor-dev.dev-web.at\/de\/wp-content\/uploads\/sites\/2\/2023\/10\/Hygrometer-scaled.jpg","width":2560,"height":1920,"caption":"Was braucht gutes Raumklima in der Husten- und Schnupfenzeit? In Unserer Miniserie kl\u00e4rt auf."},{"@type":"BreadcrumbList","@id":"https:\/\/limodor-dev.dev-web.at\/de\/2023\/10\/10\/husten-oder-durchatmen-passende-feuchte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/limodor-dev.dev-web.at\/de\/"},{"@type":"ListItem","position":2,"name":"Husten oder durchatmen? Wohlf\u00fchlfaktor Luftfeuchtigkeit"}]},{"@type":"WebSite","@id":"https:\/\/limodor-dev.dev-web.at\/de\/#website","url":"https:\/\/limodor-dev.dev-web.at\/de\/","name":"LIMODOR DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/limodor-dev.dev-web.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"","url":"https:\/\/limodor-dev.dev-web.at\/de\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/posts\/2699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/comments?post=2699"}],"version-history":[{"count":10,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/posts\/2699\/revisions"}],"predecessor-version":[{"id":7737,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/posts\/2699\/revisions\/7737"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/media\/2700"}],"wp:attachment":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/media?parent=2699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/categories?post=2699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/tags?post=2699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}