{"id":30351,"date":"2026-06-01T11:59:56","date_gmt":"2026-06-01T09:59:56","guid":{"rendered":"https:\/\/limodor-dev.dev-web.at\/de\/?post_type=product&#038;p=30351"},"modified":"2026-07-15T21:01:22","modified_gmt":"2026-07-15T19:01:22","slug":"fernbedienung-airvital-prime","status":"publish","type":"product","link":"https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/","title":{"rendered":"Fernbedienung AirVital Prime"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Fernbedienung mit Display und Hintergrundbeleuchtung sowie Touch-Bedienung zur separaten Bedienung von bis zu acht Wandl\u00fcftern Serie AIRVITAL Prime (\u00fcber Bluetooth), Farbe: wei\u00df (\u00e4hnlich RAL9016), UV-best\u00e4ndig, einschlie\u00dflich Wandhalterung. Lieferung einschlie\u00dflich 4 St\u00fcck AAA-Batterien.<\/p>\n","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":{"0":"post-30351","1":"product","2":"type-product","3":"status-publish","5":"product_cat-type","7":"first","8":"instock","9":"taxable","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fernbedienung AirVital Prime - LIMODOR<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fernbedienung AirVital Prime - LIMODOR\" \/>\n<meta property=\"og:description\" content=\"Fernbedienung mit Display und Hintergrundbeleuchtung sowie Touch-Bedienung zur separaten Bedienung von bis zu acht Wandl\u00fcftern Serie AIRVITAL Prime (\u00fcber Bluetooth), Farbe: wei\u00df (\u00e4hnlich RAL9016), UV-best\u00e4ndig, einschlie\u00dflich Wandhalterung. Lieferung einschlie\u00dflich 4 St\u00fcck AAA-Batterien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/\" \/>\n<meta property=\"og:site_name\" content=\"LIMODOR DE\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T19:01:22+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/produkt\\\/fernbedienung-airvital-prime\\\/\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/produkt\\\/fernbedienung-airvital-prime\\\/\",\"name\":\"Fernbedienung AirVital Prime - LIMODOR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/#website\"},\"datePublished\":\"2026-06-01T09:59:56+00:00\",\"dateModified\":\"2026-07-15T19:01:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/produkt\\\/fernbedienung-airvital-prime\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/produkt\\\/fernbedienung-airvital-prime\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/produkt\\\/fernbedienung-airvital-prime\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fernbedienung AirVital Prime\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/\",\"name\":\"LIMODOR DE\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/limodor-dev.dev-web.at\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fernbedienung AirVital Prime - LIMODOR","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Fernbedienung AirVital Prime - LIMODOR","og_description":"Fernbedienung mit Display und Hintergrundbeleuchtung sowie Touch-Bedienung zur separaten Bedienung von bis zu acht Wandl\u00fcftern Serie AIRVITAL Prime (\u00fcber Bluetooth), Farbe: wei\u00df (\u00e4hnlich RAL9016), UV-best\u00e4ndig, einschlie\u00dflich Wandhalterung. Lieferung einschlie\u00dflich 4 St\u00fcck AAA-Batterien.","og_url":"https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/","og_site_name":"LIMODOR DE","article_modified_time":"2026-07-15T19:01:22+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/","url":"https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/","name":"Fernbedienung AirVital Prime - LIMODOR","isPartOf":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/#website"},"datePublished":"2026-06-01T09:59:56+00:00","dateModified":"2026-07-15T19:01:22+00:00","breadcrumb":{"@id":"https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/limodor-dev.dev-web.at\/de\/produkt\/fernbedienung-airvital-prime\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/limodor-dev.dev-web.at\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/limodor-dev.dev-web.at\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Fernbedienung AirVital Prime"}]},{"@type":"WebSite","@id":"https:\/\/limodor-dev.dev-web.at\/de\/#website","url":"https:\/\/limodor-dev.dev-web.at\/de\/","name":"LIMODOR DE","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/limodor-dev.dev-web.at\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/product\/30351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/media?parent=30351"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/product_brand?post=30351"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/product_cat?post=30351"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/limodor-dev.dev-web.at\/de\/wp-json\/wp\/v2\/product_tag?post=30351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}